{"id":46,"date":"2024-07-18T16:05:28","date_gmt":"2024-07-18T16:05:28","guid":{"rendered":"https:\/\/demo.casethemes.net\/medicross\/?page_id=46"},"modified":"2024-07-18T16:05:28","modified_gmt":"2024-07-18T16:05:28","slug":"location","status":"publish","type":"page","link":"https:\/\/qrmenusystem.me\/ru\/location\/","title":{"rendered":"Location"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"46\" class=\"elementor elementor-46\">\n\t\t\t\t        <section class=\"elementor-section elementor-top-section elementor-element elementor-element-747cdb0 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible\" data-id=\"747cdb0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\n                \n                <div class=\"elementor-container elementor-column-gap-extended\">\n                <div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fcbfcfd pxl-column-none\" data-id=\"fcbfcfd\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                                <div class=\"elementor-background-overlay\"><\/div>\r\n         \r\n                <section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e8471cc elementor-section-content-bottom elementor-section-boxed elementor-section-height-default elementor-section-height-default pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible\" data-id=\"e8471cc\" data-element_type=\"section\" data-e-type=\"section\">\n\n                \n                <div class=\"elementor-container elementor-column-gap-extended\">\n                <div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e02d5be pxl-column-none pxl-column-overflow-hidden-no\" data-id=\"e02d5be\" data-element_type=\"column\" data-e-type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-ef0bafc elementor-widget__width-auto elementor-widget elementor-widget-pxl_heading\" data-id=\"ef0bafc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div id=\"pxl-pxl_heading-ef0bafc-6014\" class=\"pxl-heading px-sub-title-default-style\">\n\t<div class=\"pxl-heading--inner\">\n\t\t\n\t\t<h3 class=\"pxl-item--title style-default  highlight-default\" data-wow-delay=\"ms\">\n\t\t\t\t\tLocation\t\n\t\t\t\n\t\t<\/h3>\n\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n                <div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e2f1cbd pxl-column-none pxl-column-overflow-hidden-no\" data-id=\"e2f1cbd\" data-element_type=\"column\" data-e-type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-9bbd3b2 elementor-widget__width-auto elementor-widget elementor-widget-pxl_breadcrumb\" data-id=\"9bbd3b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_breadcrumb.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-breadcrumb-wrap\">\n\t<ul class=\"pxl-breadcrumb\"><li><span class=\"breadcrumb-entry\">Home Dental<\/span><\/li><\/ul><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t        <section class=\"elementor-section elementor-top-section elementor-element elementor-element-fc11b96 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible\" data-id=\"fc11b96\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\n                \n                <div class=\"elementor-container elementor-column-gap-extended\">\n                <div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ef89cb8 pxl-column-none\" data-id=\"ef89cb8\" data-element_type=\"column\" data-e-type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                                <div class=\"elementor-background-overlay\"><\/div>\r\n         \r\n                <section class=\"elementor-section elementor-inner-section elementor-element elementor-element-68e186f elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible\" data-id=\"68e186f\" data-element_type=\"section\" data-e-type=\"section\">\n\n                \n                <div class=\"elementor-container elementor-column-gap-extended\">\n                <div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4a4d879 pxl-column-none pxl-column-overflow-hidden-no\" data-id=\"4a4d879\" data-element_type=\"column\" data-e-type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-1c7c5e7 elementor-widget elementor-widget-pxl_text_editor\" data-id=\"1c7c5e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor default\">\n\t<div class=\"pxl-item--inner  ft-gt\" data-wow-delay=\"ms\">\n\t\t<p>With more than 25 medicross medical centers around the world, no matter where you are, We can bring you the best health care.<\/p>\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n                <div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4524402 pxl-column-none pxl-column-overflow-hidden-no\" data-id=\"4524402\" data-element_type=\"column\" data-e-type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-b6f6ffd elementor-widget__width-auto ft-gt elementor-widget elementor-widget-pxl_icon_box\" data-id=\"b6f6ffd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-icon-box pxl-icon-box1 style-2 ani3\" data-wow-delay=\"ms\">\r\n    <div class=\"pxl-item--inner\">\r\n        \r\n                            <div class=\"pxl-item--icon\">\r\n                                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"32\" height=\"32\" fill=\"#000000\" viewbox=\"0 0 256 256\"><path d=\"M152,96V56a8,8,0,0,1,16,0V76.69l34.34-34.35a8,8,0,0,1,11.32,11.32L179.32,88H200a8,8,0,0,1,0,16H160A8,8,0,0,1,152,96Zm79.88,79.08A56.26,56.26,0,0,1,176,224C96.6,224,32,159.4,32,80A56.24,56.24,0,0,1,80.92,24.13a16,16,0,0,1,16.62,9.51l21.12,47.15,0,.12A16,16,0,0,1,117.39,96c-.18.27-.37.52-.57.77L96,121.45c7.49,15.22,23.41,31,38.83,38.51l24.34-20.71a8.12,8.12,0,0,1,.75-.56,16,16,0,0,1,15.17-1.4l.13.06,47.11,21.11A16,16,0,0,1,231.88,175.08Zm-15.88-2s-.07,0-.11,0h0l-47-21.05-24.35,20.71a6.84,6.84,0,0,1-.74.56,16,16,0,0,1-15.75,1.14c-18.73-9.05-37.4-27.58-46.46-46.11a16,16,0,0,1,1-15.7,6.13,6.13,0,0,1,.57-.77L104,87.15l-21-47a.61.61,0,0,1,0-.12A40.2,40.2,0,0,0,48,80,128.14,128.14,0,0,0,176,208,40.21,40.21,0,0,0,216,173.07Z\"><\/path><\/svg>                                <\/div>\r\n                        <div class=\"pxl-item--meta\">\r\n            <h5 class=\"pxl-item--title el-empty\">\r\n                        Call Us when you Need Help!                        <\/h5>\r\n            <div class=\"pxl-item--description el-empty\">24\/7 Support:  +1 800-123-1234<\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t        <section class=\"elementor-section elementor-top-section elementor-element elementor-element-d2e30fb elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible\" data-id=\"d2e30fb\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\n                \n                <div class=\"elementor-container elementor-column-gap-default\">\n                <div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-81def60 pxl-column-none pxl-column-overflow-hidden-no\" data-id=\"81def60\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-68cfbbc elementor-widget__width-auto elementor-absolute elementor-widget elementor-widget-pxl_image\" data-id=\"68cfbbc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"pxl_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pxl_image-68cfbbc-3237\" class=\"pxl-image-single  pxl-disable-parallax-sm pxl-hide-sr-lg\" data-wow-delay=\"ms\"  >\r\n    <div class=\"pxl-item--inner\" data-wow-delay=\"120ms\">\r\n        \r\n                    <div class=\"pxl-item--image\" data-parallax-value=\"\">\r\n                                <img decoding=\"async\" width=\"28\" height=\"28\" src=\"https:\/\/qrmenusystem.me\/wp-content\/uploads\/2024\/08\/ic3.webp\" class=\"no-lazyload attachment-full\" alt=\"\" \/>                            <\/div>\r\n                \r\n    <\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0d8d0b4 elementor-widget elementor-widget-pxl_image\" data-id=\"0d8d0b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pxl_image-0d8d0b4-1438\" class=\"pxl-image-single  pxl-disable-parallax-sm pxl-hide-sr-lg\" data-wow-delay=\"ms\"  >\r\n    <div class=\"pxl-item--inner\" data-wow-delay=\"120ms\">\r\n        \r\n                    <div class=\"pxl-item--bg bg-image\" style=\"background-image: url(https:\/\/qrmenusystem.me\/wp-content\/uploads\/2024\/08\/lc.webp);\">\r\n            <\/div>\r\n                \r\n    <\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t        <section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e9b75cf elementor-section-boxed elementor-section-height-default elementor-section-height-default pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible\" data-id=\"e9b75cf\" data-element_type=\"section\" data-e-type=\"section\">\n\n                \n                <div class=\"elementor-container elementor-column-gap-default\">\n                <div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-c708ab1 pxl-column-none pxl-column-overflow-hidden-no\" data-id=\"c708ab1\" data-element_type=\"column\" data-e-type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-0229417 elementor-widget elementor-widget-pxl_heading\" data-id=\"0229417\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div id=\"pxl-pxl_heading-0229417-1574\" class=\"pxl-heading px-sub-title-default-style\">\n\t<div class=\"pxl-heading--inner\">\n\t\t\n\t\t<h3 class=\"pxl-item--title style-default  highlight-default\" data-wow-delay=\"ms\">\n\t\t\t\t\tRotterdam Office\t\n\t\t\t\n\t\t<\/h3>\n\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ae8e62e elementor-widget elementor-widget-pxl_text_editor\" data-id=\"ae8e62e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor default\">\n\t<div class=\"pxl-item--inner\" data-wow-delay=\"ms\">\n\t\t<p>NETHERLANDS<\/p>\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b6e0235 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"b6e0235\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f0f2361 elementor-widget elementor-widget-pxl_icon_box\" data-id=\"f0f2361\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-icon-box pxl-icon-box1 style-1 ani1\" data-wow-delay=\"ms\">\r\n    <div class=\"pxl-item--inner\">\r\n        \r\n                            <div class=\"pxl-item--icon\">\r\n                                    <a href=\"tel:12318005678990\">\r\n                                        <i aria-hidden=\"true\" class=\"fas fa-phone-alt\"><\/i>                                        <\/a>\r\n                            <\/div>\r\n                        <div class=\"pxl-item--meta\">\r\n            <h5 class=\"pxl-item--title el-empty\">\r\n                             <a href=\"tel:12318005678990\">\r\n                        + (123) 1800-567-8990                             <\/a>\r\n                        <\/h5>\r\n            <div class=\"pxl-item--description el-empty\"><\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c7e0bd3 elementor-widget elementor-widget-pxl_icon_box\" data-id=\"c7e0bd3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-icon-box pxl-icon-box1 style-1 ani1\" data-wow-delay=\"ms\">\r\n    <div class=\"pxl-item--inner\">\r\n        \r\n                            <div class=\"pxl-item--icon\">\r\n                                    <a href=\"mailto:medicrossmagery1806@gmail.com\">\r\n                                        <i aria-hidden=\"true\" class=\"fas fa-envelope\"><\/i>                                        <\/a>\r\n                            <\/div>\r\n                        <div class=\"pxl-item--meta\">\r\n            <h5 class=\"pxl-item--title el-empty\">\r\n                             <a href=\"mailto:medicrossmagery1806@gmail.com\">\r\n                        Medicrossmagery 1806@gmail.com                             <\/a>\r\n                        <\/h5>\r\n            <div class=\"pxl-item--description el-empty\"><\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3db726d elementor-widget elementor-widget-pxl_icon_box\" data-id=\"3db726d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-icon-box pxl-icon-box1 style-1 ani1\" data-wow-delay=\"ms\">\r\n    <div class=\"pxl-item--inner\">\r\n        \r\n                            <div class=\"pxl-item--icon\">\r\n                                    <a href=\"https:\/\/www.google.com\/maps\/search\/Old+Westbury+256\/@40.7864251,-73.6363934,13166m\/data=!3m2!1e3!4b1?hl=vi-VN&amp;entry=ttu\" target=\"_blank\">\r\n                                        <i aria-hidden=\"true\" class=\"fas fa-map-marker-alt\"><\/i>                                        <\/a>\r\n                            <\/div>\r\n                        <div class=\"pxl-item--meta\">\r\n            <h5 class=\"pxl-item--title el-empty\">\r\n                             <a href=\"https:\/\/www.google.com\/maps\/search\/Old+Westbury+256\/@40.7864251,-73.6363934,13166m\/data=!3m2!1e3!4b1?hl=vi-VN&amp;entry=ttu\" target=\"_blank\">\r\n                        Old Westbury 256, New York 11201, UK                             <\/a>\r\n                        <\/h5>\r\n            <div class=\"pxl-item--description el-empty\"><\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t            <\/div>\r\n        <\/div>\r\n                <div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1d73532 pxl-column-none pxl-column-overflow-hidden-no\" data-id=\"1d73532\" data-element_type=\"column\" data-e-type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-786571b elementor-widget elementor-widget-pxl_heading\" data-id=\"786571b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div id=\"pxl-pxl_heading-786571b-3713\" class=\"pxl-heading px-sub-title-default-style\">\n\t<div class=\"pxl-heading--inner\">\n\t\t\n\t\t<h3 class=\"pxl-item--title style-default  highlight-default\" data-wow-delay=\"ms\">\n\t\t\t\t\tDescription\t\n\t\t\t\n\t\t<\/h3>\n\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0fc5054 elementor-widget elementor-widget-pxl_text_editor\" data-id=\"0fc5054\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor default\">\n\t<div class=\"pxl-item--inner\" data-wow-delay=\"ms\">\n\t\t<p>Medicross medical center at Rotterdam Office with an area of \u200b\u200bmore than 5,000 square meters, 200 patient rooms and a campus with 5-star quality in terms of facilities and medical care. Lorem ipsum dolor sit amet, consectetur adipiscing elit. Aliquam nec faucibus leo, nec dignissim erat.<\/p>\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b9bc61 elementor-widget elementor-widget-google_maps\" data-id=\"3b9bc61\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=London%20Eye%2C%20London%2C%20United%20Kingdom&#038;t=m&#038;z=15&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"London Eye, London, United Kingdom\"\n\t\t\t\t\taria-label=\"London Eye, London, United Kingdom\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t        <section class=\"elementor-section elementor-top-section elementor-element elementor-element-4517712 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible\" data-id=\"4517712\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\n                \n                <div class=\"elementor-container elementor-column-gap-default\">\n                <div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-148cc17 pxl-column-none pxl-column-overflow-hidden-no elementor-invisible\" data-id=\"148cc17\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-54f1b56 elementor-widget elementor-widget-pxl_heading\" data-id=\"54f1b56\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div id=\"pxl-pxl_heading-54f1b56-2350\" class=\"pxl-heading px-sub-title-default-style\">\n\t<div class=\"pxl-heading--inner\">\n\t\t\n\t\t<h3 class=\"pxl-item--title style-default  highlight-default\" data-wow-delay=\"ms\">\n\t\t\t\t\tDescription\t\n\t\t\t\n\t\t<\/h3>\n\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c82e9f1 elementor-widget elementor-widget-pxl_text_editor\" data-id=\"c82e9f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor default\">\n\t<div class=\"pxl-item--inner\" data-wow-delay=\"ms\">\n\t\t<p>Medicross medical center at Rotterdam Office with an area of \u200b\u200bmore than 5,000 square meters, 200 patient rooms and a campus with 5-star quality in terms of facilities and medical care. Lorem ipsum dolor sit amet, consectetur adipiscing elit. Aliquam nec faucibus leo, nec dignissim erat.<\/p>\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a59b7e7 elementor-widget elementor-widget-google_maps\" data-id=\"a59b7e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=London%20Eye%2C%20London%2C%20United%20Kingdom&#038;t=m&#038;z=15&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"London Eye, London, United Kingdom\"\n\t\t\t\t\taria-label=\"London Eye, London, United Kingdom\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n                <div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9dac6a0 pxl-column-none pxl-column-overflow-hidden-no elementor-invisible\" data-id=\"9dac6a0\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInRight&quot;}\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-5acf970 elementor-widget__width-auto elementor-absolute elementor-widget elementor-widget-pxl_image\" data-id=\"5acf970\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"pxl_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pxl_image-5acf970-4476\" class=\"pxl-image-single  pxl-disable-parallax-sm pxl-hide-sr-lg\" data-wow-delay=\"ms\"  >\r\n    <div class=\"pxl-item--inner\" data-wow-delay=\"120ms\">\r\n        \r\n                    <div class=\"pxl-item--image\" data-parallax-value=\"\">\r\n                                <img decoding=\"async\" width=\"28\" height=\"28\" src=\"https:\/\/qrmenusystem.me\/wp-content\/uploads\/2024\/08\/ic3.webp\" class=\"no-lazyload attachment-full\" alt=\"\" \/>                            <\/div>\r\n                \r\n    <\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9a0e2ab elementor-widget elementor-widget-pxl_image\" data-id=\"9a0e2ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pxl_image-9a0e2ab-9852\" class=\"pxl-image-single  pxl-disable-parallax-sm pxl-hide-sr-lg\" data-wow-delay=\"ms\"  >\r\n    <div class=\"pxl-item--inner\" data-wow-delay=\"120ms\">\r\n        \r\n                    <div class=\"pxl-item--bg bg-image\" style=\"background-image: url(https:\/\/qrmenusystem.me\/wp-content\/uploads\/2024\/08\/lc2.webp);\">\r\n            <\/div>\r\n                \r\n    <\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t        <section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b973b2f elementor-section-boxed elementor-section-height-default elementor-section-height-default pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible\" data-id=\"b973b2f\" data-element_type=\"section\" data-e-type=\"section\">\n\n                \n                <div class=\"elementor-container elementor-column-gap-default\">\n                <div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-48f9d2d pxl-column-none pxl-column-overflow-hidden-no\" data-id=\"48f9d2d\" data-element_type=\"column\" data-e-type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-cc132a7 elementor-widget elementor-widget-pxl_heading\" data-id=\"cc132a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div id=\"pxl-pxl_heading-cc132a7-4651\" class=\"pxl-heading px-sub-title-default-style\">\n\t<div class=\"pxl-heading--inner\">\n\t\t\n\t\t<h3 class=\"pxl-item--title style-default  highlight-default\" data-wow-delay=\"ms\">\n\t\t\t\t\tBerlin Office \t\n\t\t\t\n\t\t<\/h3>\n\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d9240cb elementor-widget elementor-widget-pxl_text_editor\" data-id=\"d9240cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor default\">\n\t<div class=\"pxl-item--inner\" data-wow-delay=\"ms\">\n\t\t<p>GERMANY<\/p>\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2af8727 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"2af8727\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7239290 elementor-widget elementor-widget-pxl_icon_box\" data-id=\"7239290\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-icon-box pxl-icon-box1 style-1 ani1\" data-wow-delay=\"ms\">\r\n    <div class=\"pxl-item--inner\">\r\n        \r\n                            <div class=\"pxl-item--icon\">\r\n                                    <a href=\"tel:12318005678990\">\r\n                                        <i aria-hidden=\"true\" class=\"fas fa-phone-alt\"><\/i>                                        <\/a>\r\n                            <\/div>\r\n                        <div class=\"pxl-item--meta\">\r\n            <h5 class=\"pxl-item--title el-empty\">\r\n                             <a href=\"tel:12318005678990\">\r\n                        + (123) 1800-567-8990                             <\/a>\r\n                        <\/h5>\r\n            <div class=\"pxl-item--description el-empty\"><\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c25620 elementor-widget elementor-widget-pxl_icon_box\" data-id=\"5c25620\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-icon-box pxl-icon-box1 style-1 ani1\" data-wow-delay=\"ms\">\r\n    <div class=\"pxl-item--inner\">\r\n        \r\n                            <div class=\"pxl-item--icon\">\r\n                                    <a href=\"mailto:medicrossmagery1806@gmail.com\">\r\n                                        <i aria-hidden=\"true\" class=\"fas fa-envelope\"><\/i>                                        <\/a>\r\n                            <\/div>\r\n                        <div class=\"pxl-item--meta\">\r\n            <h5 class=\"pxl-item--title el-empty\">\r\n                             <a href=\"mailto:medicrossmagery1806@gmail.com\">\r\n                        Medicrossmagery 1806@gmail.com                             <\/a>\r\n                        <\/h5>\r\n            <div class=\"pxl-item--description el-empty\"><\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f6d80fb elementor-widget elementor-widget-pxl_icon_box\" data-id=\"f6d80fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-icon-box pxl-icon-box1 style-1 ani1\" data-wow-delay=\"ms\">\r\n    <div class=\"pxl-item--inner\">\r\n        \r\n                            <div class=\"pxl-item--icon\">\r\n                                    <a href=\"https:\/\/www.google.com\/maps\/search\/Old+Westbury+256\/@40.7864251,-73.6363934,13166m\/data=!3m2!1e3!4b1?hl=vi-VN&amp;entry=ttu\" target=\"_blank\">\r\n                                        <i aria-hidden=\"true\" class=\"fas fa-map-marker-alt\"><\/i>                                        <\/a>\r\n                            <\/div>\r\n                        <div class=\"pxl-item--meta\">\r\n            <h5 class=\"pxl-item--title el-empty\">\r\n                             <a href=\"https:\/\/www.google.com\/maps\/search\/Old+Westbury+256\/@40.7864251,-73.6363934,13166m\/data=!3m2!1e3!4b1?hl=vi-VN&amp;entry=ttu\" target=\"_blank\">\r\n                        Old Westbury 256, New York 11201, UK                             <\/a>\r\n                        <\/h5>\r\n            <div class=\"pxl-item--description el-empty\"><\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t        <section class=\"elementor-section elementor-top-section elementor-element elementor-element-0366190 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible\" data-id=\"0366190\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\n                \n                <div class=\"elementor-container elementor-column-gap-default\">\n                <div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-045d69f pxl-column-none pxl-column-overflow-hidden-no elementor-invisible\" data-id=\"045d69f\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-844a630 elementor-widget__width-auto elementor-absolute elementor-widget elementor-widget-pxl_image\" data-id=\"844a630\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"pxl_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pxl_image-844a630-8916\" class=\"pxl-image-single  pxl-disable-parallax-sm pxl-hide-sr-lg\" data-wow-delay=\"ms\"  >\r\n    <div class=\"pxl-item--inner\" data-wow-delay=\"120ms\">\r\n        \r\n                    <div class=\"pxl-item--image\" data-parallax-value=\"\">\r\n                                <img decoding=\"async\" width=\"28\" height=\"28\" src=\"https:\/\/qrmenusystem.me\/wp-content\/uploads\/2024\/08\/ic3.webp\" class=\"no-lazyload attachment-full\" alt=\"\" \/>                            <\/div>\r\n                \r\n    <\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68a76bd elementor-widget elementor-widget-pxl_image\" data-id=\"68a76bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pxl_image-68a76bd-7645\" class=\"pxl-image-single  pxl-disable-parallax-sm pxl-hide-sr-lg\" data-wow-delay=\"ms\"  >\r\n    <div class=\"pxl-item--inner\" data-wow-delay=\"120ms\">\r\n        \r\n                    <div class=\"pxl-item--bg bg-image\" style=\"background-image: url(https:\/\/qrmenusystem.me\/wp-content\/uploads\/2024\/08\/lc3-1.webp);\">\r\n            <\/div>\r\n                \r\n    <\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t        <section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d9bb4c6 elementor-section-boxed elementor-section-height-default elementor-section-height-default pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible\" data-id=\"d9bb4c6\" data-element_type=\"section\" data-e-type=\"section\">\n\n                \n                <div class=\"elementor-container elementor-column-gap-default\">\n                <div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-6c5d05b pxl-column-none pxl-column-overflow-hidden-no\" data-id=\"6c5d05b\" data-element_type=\"column\" data-e-type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-400c35e elementor-widget elementor-widget-pxl_heading\" data-id=\"400c35e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div id=\"pxl-pxl_heading-400c35e-5684\" class=\"pxl-heading px-sub-title-default-style\">\n\t<div class=\"pxl-heading--inner\">\n\t\t\n\t\t<h3 class=\"pxl-item--title style-default  highlight-default\" data-wow-delay=\"ms\">\n\t\t\t\t\tHongKong Office\n\t\n\t\t\t\n\t\t<\/h3>\n\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4ba2e6c elementor-widget elementor-widget-pxl_text_editor\" data-id=\"4ba2e6c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor default\">\n\t<div class=\"pxl-item--inner\" data-wow-delay=\"ms\">\n\t\t<p>CHINA<\/p>\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b6a942 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"1b6a942\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f48ca94 elementor-widget elementor-widget-pxl_icon_box\" data-id=\"f48ca94\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-icon-box pxl-icon-box1 style-1 ani1\" data-wow-delay=\"ms\">\r\n    <div class=\"pxl-item--inner\">\r\n        \r\n                            <div class=\"pxl-item--icon\">\r\n                                    <a href=\"tel:12318005678990\">\r\n                                        <i aria-hidden=\"true\" class=\"fas fa-phone-alt\"><\/i>                                        <\/a>\r\n                            <\/div>\r\n                        <div class=\"pxl-item--meta\">\r\n            <h5 class=\"pxl-item--title el-empty\">\r\n                             <a href=\"tel:12318005678990\">\r\n                        + (123) 1800-567-8990                             <\/a>\r\n                        <\/h5>\r\n            <div class=\"pxl-item--description el-empty\"><\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a1ac74 elementor-widget elementor-widget-pxl_icon_box\" data-id=\"4a1ac74\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-icon-box pxl-icon-box1 style-1 ani1\" data-wow-delay=\"ms\">\r\n    <div class=\"pxl-item--inner\">\r\n        \r\n                            <div class=\"pxl-item--icon\">\r\n                                    <a href=\"mailto:medicrossmagery1806@gmail.com\">\r\n                                        <i aria-hidden=\"true\" class=\"fas fa-envelope\"><\/i>                                        <\/a>\r\n                            <\/div>\r\n                        <div class=\"pxl-item--meta\">\r\n            <h5 class=\"pxl-item--title el-empty\">\r\n                             <a href=\"mailto:medicrossmagery1806@gmail.com\">\r\n                        Medicrossmagery 1806@gmail.com                             <\/a>\r\n                        <\/h5>\r\n            <div class=\"pxl-item--description el-empty\"><\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ef5412 elementor-widget elementor-widget-pxl_icon_box\" data-id=\"2ef5412\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-icon-box pxl-icon-box1 style-1 ani1\" data-wow-delay=\"ms\">\r\n    <div class=\"pxl-item--inner\">\r\n        \r\n                            <div class=\"pxl-item--icon\">\r\n                                    <a href=\"https:\/\/www.google.com\/maps\/search\/Old+Westbury+256\/@40.7864251,-73.6363934,13166m\/data=!3m2!1e3!4b1?hl=vi-VN&amp;entry=ttu\" target=\"_blank\">\r\n                                        <i aria-hidden=\"true\" class=\"fas fa-map-marker-alt\"><\/i>                                        <\/a>\r\n                            <\/div>\r\n                        <div class=\"pxl-item--meta\">\r\n            <h5 class=\"pxl-item--title el-empty\">\r\n                             <a href=\"https:\/\/www.google.com\/maps\/search\/Old+Westbury+256\/@40.7864251,-73.6363934,13166m\/data=!3m2!1e3!4b1?hl=vi-VN&amp;entry=ttu\" target=\"_blank\">\r\n                        Old Westbury 256, New York 11201, UK                             <\/a>\r\n                        <\/h5>\r\n            <div class=\"pxl-item--description el-empty\"><\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t            <\/div>\r\n        <\/div>\r\n                <div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5d30a47 pxl-column-none pxl-column-overflow-hidden-no elementor-invisible\" data-id=\"5d30a47\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;}\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-b3a3418 elementor-widget elementor-widget-pxl_heading\" data-id=\"b3a3418\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div id=\"pxl-pxl_heading-b3a3418-7524\" class=\"pxl-heading px-sub-title-default-style\">\n\t<div class=\"pxl-heading--inner\">\n\t\t\n\t\t<h3 class=\"pxl-item--title style-default  highlight-default\" data-wow-delay=\"ms\">\n\t\t\t\t\tDescription\t\n\t\t\t\n\t\t<\/h3>\n\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d69e927 elementor-widget elementor-widget-pxl_text_editor\" data-id=\"d69e927\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor default\">\n\t<div class=\"pxl-item--inner\" data-wow-delay=\"ms\">\n\t\t<p>Medicross medical center at Rotterdam Office with an area of \u200b\u200bmore than 5,000 square meters, 200 patient rooms and a campus with 5-star quality in terms of facilities and medical care. Lorem ipsum dolor sit amet, consectetur adipiscing elit. Aliquam nec faucibus leo, nec dignissim erat.<\/p>\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7fd5b83 elementor-widget elementor-widget-google_maps\" data-id=\"7fd5b83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=London%20Eye%2C%20London%2C%20United%20Kingdom&#038;t=m&#038;z=15&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"London Eye, London, United Kingdom\"\n\t\t\t\t\taria-label=\"London Eye, London, United Kingdom\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Location Home 1 With more than 25 medicross medical centers around the world, no matter where you are, We can bring you the best health care. Call Us when you Need Help! 24\/7 Support: +1 800-123-1234 Rotterdam Office NETHERLANDS + (123) 1800-567-8990 Medicrossmagery 1806@gmail.com Old Westbury 256, New York 11201, UK Description Medicross medical center [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-46","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/qrmenusystem.me\/ru\/wp-json\/wp\/v2\/pages\/46","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/qrmenusystem.me\/ru\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/qrmenusystem.me\/ru\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/qrmenusystem.me\/ru\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/qrmenusystem.me\/ru\/wp-json\/wp\/v2\/comments?post=46"}],"version-history":[{"count":0,"href":"https:\/\/qrmenusystem.me\/ru\/wp-json\/wp\/v2\/pages\/46\/revisions"}],"wp:attachment":[{"href":"https:\/\/qrmenusystem.me\/ru\/wp-json\/wp\/v2\/media?parent=46"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}